{"id":4039,"date":"2025-03-19T10:20:07","date_gmt":"2025-03-19T02:20:07","guid":{"rendered":"https:\/\/www.seyountyre.com\/?post_type=product&#038;p=4039"},"modified":"2025-12-09T14:01:08","modified_gmt":"2025-12-09T06:01:08","slug":"seyoun-bike-tire-sy-eb001-26x2-1-2-fat-bicycle-tyre","status":"publish","type":"product","link":"https:\/\/www.seyountyre.com\/zh\/bicycle-tire\/seyoun-bike-tire-sy-eb001-26x2-1-2-fat-bicycle-tyre\/","title":{"rendered":"SEYOUN Bike Tire SY-EB001 26X2 1\/2 Fat Bicycle Tyre"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-4037 size-full\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/1741764250716.png\" alt=\"\" width=\"959\" height=\"85\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/1741764250716.png 959w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/1741764250716-300x27.png 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/1741764250716-768x68.png 768w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/1741764250716-600x53.png 600w\" sizes=\"(max-width: 959px) 100vw, 959px\" \/><\/p>\n<p><img decoding=\"async\" class=\"alignnone  wp-image-4277\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4ea7\u54c1\u4ecb\u7ecd-300x32.jpg\" alt=\"\" width=\"544\" height=\"58\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4ea7\u54c1\u4ecb\u7ecd-300x32.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4ea7\u54c1\u4ecb\u7ecd-18x2.jpg 18w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4ea7\u54c1\u4ecb\u7ecd-600x63.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4ea7\u54c1\u4ecb\u7ecd.jpg 750w\" sizes=\"(max-width: 544px) 100vw, 544px\" \/><\/p>\n<p><img decoding=\"async\" class=\"alignnone  wp-image-4364\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4e09\u5143\u56fd\u9645\u7ad9-\u81ea\u884c\u8f66_02-300x236.jpg\" alt=\"\" width=\"547\" height=\"430\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4e09\u5143\u56fd\u9645\u7ad9-\u81ea\u884c\u8f66_02-300x236.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4e09\u5143\u56fd\u9645\u7ad9-\u81ea\u884c\u8f66_02-15x12.jpg 15w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4e09\u5143\u56fd\u9645\u7ad9-\u81ea\u884c\u8f66_02-600x472.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4e09\u5143\u56fd\u9645\u7ad9-\u81ea\u884c\u8f66_02.jpg 750w\" sizes=\"(max-width: 547px) 100vw, 547px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-4279\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/Truck_02-300x25.jpg\" alt=\"\" width=\"552\" height=\"46\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/Truck_02-300x25.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/Truck_02-18x1.jpg 18w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/Truck_02-600x50.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/Truck_02.jpg 750w\" sizes=\"(max-width: 552px) 100vw, 552px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-4366\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4e09\u5143\u56fd\u9645\u7ad9-\u81ea\u884c\u8f66_16-300x290.jpg\" alt=\"\" width=\"556\" height=\"537\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4e09\u5143\u56fd\u9645\u7ad9-\u81ea\u884c\u8f66_16-300x290.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4e09\u5143\u56fd\u9645\u7ad9-\u81ea\u884c\u8f66_16-12x12.jpg 12w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4e09\u5143\u56fd\u9645\u7ad9-\u81ea\u884c\u8f66_16-600x580.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4e09\u5143\u56fd\u9645\u7ad9-\u81ea\u884c\u8f66_16.jpg 750w\" sizes=\"(max-width: 556px) 100vw, 556px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-4365\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4e09\u5143\u56fd\u9645\u7ad9-\u81ea\u884c\u8f66_04-300x153.jpg\" alt=\"\" width=\"549\" height=\"280\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4e09\u5143\u56fd\u9645\u7ad9-\u81ea\u884c\u8f66_04-300x153.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4e09\u5143\u56fd\u9645\u7ad9-\u81ea\u884c\u8f66_04-18x9.jpg 18w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4e09\u5143\u56fd\u9645\u7ad9-\u81ea\u884c\u8f66_04-600x306.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4e09\u5143\u56fd\u9645\u7ad9-\u81ea\u884c\u8f66_04.jpg 750w\" sizes=\"(max-width: 549px) 100vw, 549px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-4367\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u81ea\u884c\u8f66\u597d\u8bc4-300x300.jpg\" alt=\"\" width=\"545\" height=\"545\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u81ea\u884c\u8f66\u597d\u8bc4-300x300.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u81ea\u884c\u8f66\u597d\u8bc4-150x150.jpg 150w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u81ea\u884c\u8f66\u597d\u8bc4-12x12.jpg 12w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u81ea\u884c\u8f66\u597d\u8bc4-600x600.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u81ea\u884c\u8f66\u597d\u8bc4-100x100.jpg 100w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u81ea\u884c\u8f66\u597d\u8bc4.jpg 750w\" sizes=\"(max-width: 545px) 100vw, 545px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-4284\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u516c\u53f8\u7b80\u4ecb-300x28.jpg\" alt=\"\" width=\"525\" height=\"49\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u516c\u53f8\u7b80\u4ecb-300x28.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u516c\u53f8\u7b80\u4ecb-18x2.jpg 18w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u516c\u53f8\u7b80\u4ecb-600x55.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u516c\u53f8\u7b80\u4ecb.jpg 750w\" sizes=\"(max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-4285\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u516c\u53f8\u4ecb\u7ecd\u56fe-300x146.jpg\" alt=\"\" width=\"532\" height=\"259\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u516c\u53f8\u4ecb\u7ecd\u56fe-300x146.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u516c\u53f8\u4ecb\u7ecd\u56fe-18x9.jpg 18w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u516c\u53f8\u4ecb\u7ecd\u56fe-600x292.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u516c\u53f8\u4ecb\u7ecd\u56fe.jpg 750w\" sizes=\"(max-width: 532px) 100vw, 532px\" \/><\/p>\n<div class=\"J_module\">\n<div class=\"detail-decorate-json-renderer-container\">\n<div class=\"magic-61\">\n<div class=\"magic-62\">\n<div class=\"magic-63\">\n<div class=\"magic-64\">\n<div>\n<div class=\"magic-65\"><span class=\"magic-21\"><span class=\"magic-66\" style=\"color: #d67b03;\" data-spm-anchor-id=\"a2700.details-description.0.i0.3214tYHntYHnTh\">\u6c5f\u82cf\u4e09\u5143\u8f6e\u80ce\u6709\u9650\u516c\u53f8<\/span> <\/span><span class=\"magic-67\">(\u8d5b\u8f6e\u8f6e\u80ce), \u6210\u7acb\u4e8e2001\u5e74\uff0c\u662f\u4e00\u5bb6\u6c11\u8425\u79d1\u6280\u8f6e\u80ce\u548c\u5185\u80ce\u5236\u9020\u5546\uff0c\u4ea7\u54c1\u6db5\u76d6\u81ea\u884c\u8f66\u3001\u7535\u52a8\u81ea\u884c\u8f66\u3001\u6469\u6258\u8f66\u548c\u5361\u8f66\u3002\u8d5b\u8f6e\u603b\u90e8\uff0c\u4e5f\u662f\u5176\u4e3b\u8981\u751f\u4ea7\u57fa\u5730\uff0c\u5bbf\u8fc1\u5de5\u5382\uff0c\u6210\u7acb\u4e8e2007\u5e747\u67087\u65e5\uff0c\u5750\u843d\u4e8e\u6c5f\u82cf\u7701\u5bbf\u8fc1\u5e02\u5bbf\u8c6b\u7ecf\u6d4e\u5f00\u53d1\u533a\uff0c\u5730\u7406\u4f4d\u7f6e\u4f18\u8d8a\u3002\u5382\u533a\u5360\u5730648\u4ea9\uff0c\u5efa\u7b51\u9762\u79ef29\u4e07\u5e73\u65b9\u7c73\u3002\u603b\u6295\u8d442.9\u4ebf\u7f8e\u5143\uff0c\u5bbf\u8fc1\u5de5\u5382\u5df2\u5efa\u621043\u6761\u4e16\u754c\u7ea7\u751f\u4ea7\u7ebf\u3002\u8d5b\u8f6e\u8f6e\u80ce\u662f\u5168\u7403\u6700\u5927\u7684\u5236\u9020\u5546\u4e4b\u4e00\uff0c\u5e74\u4ea7\u81ea\u884c\u8f66\u3001\u7535\u52a8\u81ea\u884c\u8f66\u3001\u6469\u6258\u8f66\u548c\u5361\u8f66\u5185\u5916\u80ce8000\u4e07\u6761\uff0c\u5e74\u9500\u552e\u989d\u8fbe1.5\u4ebf\u7f8e\u5143\u3002\u8d5b\u8f6e\u8f6e\u80ce\u662f\u4e2d\u56fd\u6469\u6258\u8f66\u548c\u8e0f\u677f\u8f66\u8f6e\u80ce\u5236\u9020\u5546\u524d\u4e09\u5f3a\uff0c\u5e76\u4e8e2021\u5e74\u6295\u8d4430\u4ebf\u5143\u4eba\u6c11\u5e01\uff0c\u63a8\u51fa\u4e86\u5168\u81ea\u52a8\u5316\u751f\u4ea7\u7ebf\uff0c\u5b9e\u73b0\u4e86\u4e2d\u56fd\u9996\u4e2a\u771f\u6b63\u7684\u5de5\u4e1a4.0\u3002\u8d5b\u8f6e\u8f6e\u80ce\u5df2\u83b7\u5f97ISO9001\u3001CCC\u3001E-MARK\u3001ECE\u3001SNI\u548cDOT\u8ba4\u8bc1\u3002\u51ed\u501f our ISO9001 \u8d28\u91cf\u7ba1\u7406\u4f53\u7cfb\u8ba4\u8bc1\u548c\u5f3a\u5236\u6027\u4ea7\u54c1\u8ba4\u8bc1 (3C \u8ba4\u8bc1)\uff0c\u6211\u4eec\u5efa\u7acb\u4e86\u4e00\u4e2a\u5168\u9762\u7684\u8d28\u91cf\u7ba1\u7406\u4f53\u7cfb\u548c\u6d41\u7a0b\u3002 <\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"J_module\">\n<div class=\"icbu-pc-detailManyImage magic-68\"><\/div>\n<\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-4292\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5de5\u5382\u8be6\u60c5\u56fe-300x266.jpg\" alt=\"\" width=\"513\" height=\"455\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5de5\u5382\u8be6\u60c5\u56fe-300x266.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5de5\u5382\u8be6\u60c5\u56fe-14x12.jpg 14w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5de5\u5382\u8be6\u60c5\u56fe-600x532.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5de5\u5382\u8be6\u60c5\u56fe.jpg 750w\" sizes=\"(max-width: 513px) 100vw, 513px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-4287\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u8bc1\u4e66-300x28.jpg\" alt=\"\" width=\"514\" height=\"48\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u8bc1\u4e66-300x28.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u8bc1\u4e66-18x2.jpg 18w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u8bc1\u4e66-600x56.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u8bc1\u4e66.jpg 750w\" sizes=\"(max-width: 514px) 100vw, 514px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-4286\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u6469\u6258\u8f66\u91c7\u75282_08-300x131.jpg\" alt=\"\" width=\"515\" height=\"225\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u6469\u6258\u8f66\u91c7\u75282_08-300x131.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u6469\u6258\u8f66\u91c7\u75282_08-18x8.jpg 18w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u6469\u6258\u8f66\u91c7\u75282_08-600x262.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u6469\u6258\u8f66\u91c7\u75282_08.jpg 750w\" sizes=\"(max-width: 515px) 100vw, 515px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-4288\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5c55\u4f1a\u56fe-300x300.jpg\" alt=\"\" width=\"489\" height=\"489\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5c55\u4f1a\u56fe-300x300.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5c55\u4f1a\u56fe-1024x1024.jpg 1024w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5c55\u4f1a\u56fe-150x150.jpg 150w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5c55\u4f1a\u56fe-768x768.jpg 768w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5c55\u4f1a\u56fe-12x12.jpg 12w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5c55\u4f1a\u56fe-600x600.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5c55\u4f1a\u56fe-100x100.jpg 100w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5c55\u4f1a\u56fe.jpg 1200w\" sizes=\"(max-width: 489px) 100vw, 489px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-4283\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u88c5\u7bb1\u53d1\u8d27\u56fe-300x236.jpg\" alt=\"\" width=\"489\" height=\"385\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u88c5\u7bb1\u53d1\u8d27\u56fe-300x236.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u88c5\u7bb1\u53d1\u8d27\u56fe-15x12.jpg 15w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u88c5\u7bb1\u53d1\u8d27\u56fe-600x473.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u88c5\u7bb1\u53d1\u8d27\u56fe.jpg 750w\" sizes=\"(max-width: 489px) 100vw, 489px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>JiangsuSanyuan Tire Co., Ltd (SEYOUN Tire),founded in 2001,is privately technology manufacturers of tires and tubes for bicycles, electric bicycles, motorcycles and trucks. SEYOUN headquater, as its main manufacturing base,Suqian Factory, founded on 7 July, 2007,is conveniently located at Suyu economy development district in Suqian city, Jiangsu province. Covering an area of 648 acres, with the [&hellip;]<\/p>\n","protected":false},"featured_media":4040,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[45],"product_tag":[],"class_list":{"0":"post-4039","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-bicycle-tire","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.seyountyre.com\/zh\/wp-json\/wp\/v2\/product\/4039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.seyountyre.com\/zh\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.seyountyre.com\/zh\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.seyountyre.com\/zh\/wp-json\/wp\/v2\/comments?post=4039"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.seyountyre.com\/zh\/wp-json\/wp\/v2\/media\/4040"}],"wp:attachment":[{"href":"https:\/\/www.seyountyre.com\/zh\/wp-json\/wp\/v2\/media?parent=4039"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.seyountyre.com\/zh\/wp-json\/wp\/v2\/product_brand?post=4039"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.seyountyre.com\/zh\/wp-json\/wp\/v2\/product_cat?post=4039"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.seyountyre.com\/zh\/wp-json\/wp\/v2\/product_tag?post=4039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}