{"id":3391,"date":"2025-03-10T15:18:23","date_gmt":"2025-03-10T07:18:23","guid":{"rendered":"https:\/\/www.seyountyre.com\/?post_type=product&#038;p=3391"},"modified":"2026-01-21T13:53:56","modified_gmt":"2026-01-21T05:53:56","slug":"seyoun-high-speed-motorcycle-tire-sy-s068-3-00-12-3-50-12-3-75-12-4-00-12-4-50-12-5-00-12-llantas-para-moto-tyre","status":"publish","type":"product","link":"https:\/\/www.seyountyre.com\/it\/high-speed-motorcycle-tire\/seyoun-high-speed-motorcycle-tire-sy-s068-3-00-12-3-50-12-3-75-12-4-00-12-4-50-12-5-00-12-llantas-para-moto-tyre\/","title":{"rendered":"SEYOUN High Speed Motorcycle Tire SY-S068 3.00-12 3.50-12 3.75-12 4.00-12 4.50-12 5.00-12 Llantas Para Moto Tyre"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-3392\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/17415758429121.png\" alt=\"\" width=\"1019\" height=\"374\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/17415758429121.png 1649w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/17415758429121-300x110.png 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/17415758429121-1024x376.png 1024w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/17415758429121-768x282.png 768w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/17415758429121-1536x564.png 1536w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/17415758429121-600x220.png 600w\" sizes=\"(max-width: 1019px) 100vw, 1019px\" \/><\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-4279\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/Truck_02-300x25.jpg\" alt=\"\" width=\"648\" height=\"54\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/Truck_02-300x25.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/Truck_02-18x1.jpg 18w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/Truck_02-600x50.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/Truck_02.jpg 750w\" sizes=\"(max-width: 648px) 100vw, 648px\" \/><\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-4510\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u66f4\u591a\u82b1\u7eb9\u56fe_01-1-270x300.jpg\" alt=\"\" width=\"649\" height=\"721\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u66f4\u591a\u82b1\u7eb9\u56fe_01-1-270x300.jpg 270w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u66f4\u591a\u82b1\u7eb9\u56fe_01-1-11x12.jpg 11w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u66f4\u591a\u82b1\u7eb9\u56fe_01-1-600x666.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u66f4\u591a\u82b1\u7eb9\u56fe_01-1.jpg 750w\" sizes=\"(max-width: 649px) 100vw, 649px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4295\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4ea7\u54c1\u5b9a\u5236-300x157.jpg\" alt=\"\" width=\"611\" height=\"320\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4ea7\u54c1\u5b9a\u5236-300x157.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4ea7\u54c1\u5b9a\u5236-18x9.jpg 18w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4ea7\u54c1\u5b9a\u5236-600x314.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4ea7\u54c1\u5b9a\u5236.jpg 750w\" sizes=\"(max-width: 611px) 100vw, 611px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4352\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u672a\u6807\u9898-2_01-286x300.jpg\" alt=\"\" width=\"593\" height=\"622\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u672a\u6807\u9898-2_01-286x300.jpg 286w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u672a\u6807\u9898-2_01-11x12.jpg 11w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u672a\u6807\u9898-2_01-600x630.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u672a\u6807\u9898-2_01.jpg 750w\" sizes=\"(max-width: 593px) 100vw, 593px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4284\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u516c\u53f8\u7b80\u4ecb-300x28.jpg\" alt=\"\" width=\"579\" height=\"54\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u516c\u53f8\u7b80\u4ecb-300x28.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u516c\u53f8\u7b80\u4ecb-18x2.jpg 18w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u516c\u53f8\u7b80\u4ecb-600x55.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u516c\u53f8\u7b80\u4ecb.jpg 750w\" sizes=\"(max-width: 579px) 100vw, 579px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4285\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u516c\u53f8\u4ecb\u7ecd\u56fe-300x146.jpg\" alt=\"\" width=\"586\" height=\"285\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u516c\u53f8\u4ecb\u7ecd\u56fe-300x146.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u516c\u53f8\u4ecb\u7ecd\u56fe-18x9.jpg 18w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u516c\u53f8\u4ecb\u7ecd\u56fe-600x292.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u516c\u53f8\u4ecb\u7ecd\u56fe.jpg 750w\" sizes=\"(max-width: 586px) 100vw, 586px\" \/><\/p>\n<p><span class=\"magic-20\"><span class=\"magic-62\" style=\"color: #d67b03;\" data-spm-anchor-id=\"a2700.details-description.0.i0.2129JDpcJDpcSy\">Pneumatici JiangsuSanyuan Co., Ltd<\/span> <\/span><span class=\"magic-34\">(SEYOUN Tire), fondata nel 2001, \u00e8 un produttore privato di pneumatici e camere d'aria per biciclette, biciclette elettriche, motociclette e camion. Il quartier generale di SEYOUN, cos\u00ec come la sua principale base produttiva, la Fabbrica di Suqian, fondata il 7 luglio 2007, si trova convenientemente nel distretto di sviluppo economico di Suyu, nella citt\u00e0 di Suqian, provincia di Jiangsu. Copre un'area di 648 acri, con un'area edificata di 290.000 metri quadrati. Con un investimento totale di 290 milioni di dollari, la Fabbrica di Suqian ha costruito oltre 43 linee di produzione di livello mondiale. SEYOUN Tire \u00e8 uno dei maggiori produttori mondiali con una produzione di 80 milioni di camere d'aria e 83 milioni di pneumatici per biciclette, biciclette elettriche, motociclette e camion, e le sue vendite annuali raggiungono i 150 milioni di dollari. SEYOUN tire \u00e8 uno dei TOP 3 produttori di pneumatici per motociclette e scooter in Cina e abbiamo investito 3 miliardi di RMB nel 2021 per lanciare la linea di produzione completamente automatica per realizzare la prima vera industria 4.0 in Cina. SEYOUN Tire ha ottenuto le certificazioni ISO9001, CCC, E-MARK, ECE, SNI e DOT. Con la nostra certificazione del sistema di gestione della qualit\u00e0 ISO9001 e le certificazioni obbligatorie di prodotto (certificazione 3C), abbiamo stabilito un sistema e processi completi di gestione della qualit\u00e0. <\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4292\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5de5\u5382\u8be6\u60c5\u56fe-300x266.jpg\" alt=\"\" width=\"552\" height=\"489\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5de5\u5382\u8be6\u60c5\u56fe-300x266.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5de5\u5382\u8be6\u60c5\u56fe-14x12.jpg 14w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5de5\u5382\u8be6\u60c5\u56fe-600x532.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5de5\u5382\u8be6\u60c5\u56fe.jpg 750w\" sizes=\"(max-width: 552px) 100vw, 552px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4287\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u8bc1\u4e66-300x28.jpg\" alt=\"\" width=\"546\" height=\"51\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u8bc1\u4e66-300x28.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u8bc1\u4e66-18x2.jpg 18w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u8bc1\u4e66-600x56.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u8bc1\u4e66.jpg 750w\" sizes=\"(max-width: 546px) 100vw, 546px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4286\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u6469\u6258\u8f66\u91c7\u75282_08-300x131.jpg\" alt=\"\" width=\"552\" height=\"241\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u6469\u6258\u8f66\u91c7\u75282_08-300x131.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u6469\u6258\u8f66\u91c7\u75282_08-18x8.jpg 18w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u6469\u6258\u8f66\u91c7\u75282_08-600x262.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u6469\u6258\u8f66\u91c7\u75282_08.jpg 750w\" sizes=\"(max-width: 552px) 100vw, 552px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4288\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5c55\u4f1a\u56fe-300x300.jpg\" alt=\"\" width=\"531\" height=\"531\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5c55\u4f1a\u56fe-300x300.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5c55\u4f1a\u56fe-1024x1024.jpg 1024w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5c55\u4f1a\u56fe-150x150.jpg 150w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5c55\u4f1a\u56fe-768x768.jpg 768w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5c55\u4f1a\u56fe-12x12.jpg 12w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5c55\u4f1a\u56fe-600x600.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5c55\u4f1a\u56fe-100x100.jpg 100w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5c55\u4f1a\u56fe.jpg 1200w\" sizes=\"(max-width: 531px) 100vw, 531px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4283\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u88c5\u7bb1\u53d1\u8d27\u56fe-300x236.jpg\" alt=\"\" width=\"529\" height=\"416\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u88c5\u7bb1\u53d1\u8d27\u56fe-300x236.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u88c5\u7bb1\u53d1\u8d27\u56fe-15x12.jpg 15w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u88c5\u7bb1\u53d1\u8d27\u56fe-600x473.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u88c5\u7bb1\u53d1\u8d27\u56fe.jpg 750w\" sizes=\"(max-width: 529px) 100vw, 529px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>JiangsuSanyuan Tire Co., Ltd (SEYOUN Tire),founded in 2001,is privately technology manufacturers of tires and tubes for bicycles, electric bicycles, motorcycles and trucks. SEYOUN headquater, as its main manufacturing base,Suqian Factory, founded on 7 July, 2007,is conveniently located at Suyu economy development district in Suqian city, Jiangsu province. Covering an area of 648 acres, with the [&hellip;]<\/p>\n","protected":false},"featured_media":3393,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[24],"product_tag":[],"class_list":{"0":"post-3391","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-high-speed-motorcycle-tire","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.seyountyre.com\/it\/wp-json\/wp\/v2\/product\/3391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.seyountyre.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.seyountyre.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.seyountyre.com\/it\/wp-json\/wp\/v2\/comments?post=3391"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.seyountyre.com\/it\/wp-json\/wp\/v2\/media\/3393"}],"wp:attachment":[{"href":"https:\/\/www.seyountyre.com\/it\/wp-json\/wp\/v2\/media?parent=3391"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.seyountyre.com\/it\/wp-json\/wp\/v2\/product_brand?post=3391"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.seyountyre.com\/it\/wp-json\/wp\/v2\/product_cat?post=3391"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.seyountyre.com\/it\/wp-json\/wp\/v2\/product_tag?post=3391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}