{"id":4003,"date":"2025-03-19T09:23:42","date_gmt":"2025-03-19T01:23:42","guid":{"rendered":"https:\/\/www.seyountyre.com\/?post_type=product&#038;p=4003"},"modified":"2025-12-11T14:21:25","modified_gmt":"2025-12-11T06:21:25","slug":"seyoun-sy-1181-bicycle-tyre-16x1-95-20x1-95-24x1-95-26x1-95-28x1-95-bike-tire","status":"publish","type":"product","link":"https:\/\/www.seyountyre.com\/es\/bicycle-tire\/seyoun-sy-1181-bicycle-tyre-16x1-95-20x1-95-24x1-95-26x1-95-28x1-95-bike-tire\/","title":{"rendered":"SEYOUN SY-1181 Bicycle Tyre 16X1.95 20X1.95 24X1.95 26X1.95 28X1.95 Bike Tire"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-3998 size-full\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/1741764140220.png\" alt=\"\" width=\"947\" height=\"185\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/1741764140220.png 947w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/1741764140220-300x59.png 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/1741764140220-768x150.png 768w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/1741764140220-600x117.png 600w\" sizes=\"(max-width: 947px) 100vw, 947px\" \/><\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-4277\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4ea7\u54c1\u4ecb\u7ecd-300x32.jpg\" alt=\"\" width=\"638\" height=\"68\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4ea7\u54c1\u4ecb\u7ecd-300x32.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4ea7\u54c1\u4ecb\u7ecd-18x2.jpg 18w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4ea7\u54c1\u4ecb\u7ecd-600x63.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4ea7\u54c1\u4ecb\u7ecd.jpg 750w\" sizes=\"(max-width: 638px) 100vw, 638px\" \/><\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-4364\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4e09\u5143\u56fd\u9645\u7ad9-\u81ea\u884c\u8f66_02-300x236.jpg\" alt=\"\" width=\"627\" height=\"493\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4e09\u5143\u56fd\u9645\u7ad9-\u81ea\u884c\u8f66_02-300x236.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4e09\u5143\u56fd\u9645\u7ad9-\u81ea\u884c\u8f66_02-15x12.jpg 15w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4e09\u5143\u56fd\u9645\u7ad9-\u81ea\u884c\u8f66_02-600x472.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4e09\u5143\u56fd\u9645\u7ad9-\u81ea\u884c\u8f66_02.jpg 750w\" sizes=\"(max-width: 627px) 100vw, 627px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4279\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/Truck_02-300x25.jpg\" alt=\"\" width=\"624\" height=\"52\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/Truck_02-300x25.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/Truck_02-18x1.jpg 18w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/Truck_02-600x50.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/Truck_02.jpg 750w\" sizes=\"(max-width: 624px) 100vw, 624px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4366\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4e09\u5143\u56fd\u9645\u7ad9-\u81ea\u884c\u8f66_16-300x290.jpg\" alt=\"\" width=\"631\" height=\"610\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4e09\u5143\u56fd\u9645\u7ad9-\u81ea\u884c\u8f66_16-300x290.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4e09\u5143\u56fd\u9645\u7ad9-\u81ea\u884c\u8f66_16-12x12.jpg 12w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4e09\u5143\u56fd\u9645\u7ad9-\u81ea\u884c\u8f66_16-600x580.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4e09\u5143\u56fd\u9645\u7ad9-\u81ea\u884c\u8f66_16.jpg 750w\" sizes=\"(max-width: 631px) 100vw, 631px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4382\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/11-e1765349972684-300x112.jpg\" alt=\"\" width=\"613\" height=\"229\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/11-e1765349972684-300x112.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/11-e1765349972684-18x7.jpg 18w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/11-e1765349972684-600x225.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/11-e1765349972684.jpg 750w\" sizes=\"(max-width: 613px) 100vw, 613px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4365\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4e09\u5143\u56fd\u9645\u7ad9-\u81ea\u884c\u8f66_04-300x153.jpg\" alt=\"\" width=\"614\" height=\"313\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4e09\u5143\u56fd\u9645\u7ad9-\u81ea\u884c\u8f66_04-300x153.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4e09\u5143\u56fd\u9645\u7ad9-\u81ea\u884c\u8f66_04-18x9.jpg 18w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4e09\u5143\u56fd\u9645\u7ad9-\u81ea\u884c\u8f66_04-600x306.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u4e09\u5143\u56fd\u9645\u7ad9-\u81ea\u884c\u8f66_04.jpg 750w\" sizes=\"(max-width: 614px) 100vw, 614px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4367\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u81ea\u884c\u8f66\u597d\u8bc4-300x300.jpg\" alt=\"\" width=\"595\" height=\"595\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u81ea\u884c\u8f66\u597d\u8bc4-300x300.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u81ea\u884c\u8f66\u597d\u8bc4-150x150.jpg 150w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u81ea\u884c\u8f66\u597d\u8bc4-12x12.jpg 12w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u81ea\u884c\u8f66\u597d\u8bc4-600x600.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u81ea\u884c\u8f66\u597d\u8bc4-100x100.jpg 100w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u81ea\u884c\u8f66\u597d\u8bc4.jpg 750w\" sizes=\"(max-width: 595px) 100vw, 595px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4284\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u516c\u53f8\u7b80\u4ecb-300x28.jpg\" alt=\"\" width=\"579\" height=\"54\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u516c\u53f8\u7b80\u4ecb-300x28.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u516c\u53f8\u7b80\u4ecb-18x2.jpg 18w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u516c\u53f8\u7b80\u4ecb-600x55.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u516c\u53f8\u7b80\u4ecb.jpg 750w\" sizes=\"(max-width: 579px) 100vw, 579px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4285\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u516c\u53f8\u4ecb\u7ecd\u56fe-300x146.jpg\" alt=\"\" width=\"573\" height=\"279\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u516c\u53f8\u4ecb\u7ecd\u56fe-300x146.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u516c\u53f8\u4ecb\u7ecd\u56fe-18x9.jpg 18w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u516c\u53f8\u4ecb\u7ecd\u56fe-600x292.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u516c\u53f8\u4ecb\u7ecd\u56fe.jpg 750w\" sizes=\"(max-width: 573px) 100vw, 573px\" \/><\/p>\n<p><span class=\"magic-20\"><span class=\"magic-62\" style=\"color: #d67b03;\" data-spm-anchor-id=\"a2700.details-description.0.i0.2129JDpcJDpcSy\">JiangsuSanyuan Tire Co., Ltd<\/span> <\/span><span class=\"magic-34\">(SEYOUN Tire),fundada en 2001, es un fabricante privado de tecnolog\u00eda de neum\u00e1ticos y c\u00e1maras para bicicletas, bicicletas el\u00e9ctricas, motocicletas y camiones. La sede de SEYOUN, como su principal base de fabricaci\u00f3n, la f\u00e1brica de Suqian, fundada el 7 de julio de 2007, est\u00e1 convenientemente ubicada en el distrito de desarrollo econ\u00f3mico de Suyu en la ciudad de Suqian, provincia de Jiangsu. Cubriendo un \u00e1rea de 648 acres, con un \u00e1rea de construcci\u00f3n de 290.000 metros cuadrados. Con una inversi\u00f3n total de 290 millones de d\u00f3lares, la F\u00e1brica de Suqian ha construido m\u00e1s de 43 l\u00edneas de producci\u00f3n de clase mundial. SEYOUN Tire es uno de los mayores fabricantes del mundo con una producci\u00f3n de 80 millones de c\u00e1maras y 83 millones de neum\u00e1ticos para bicicletas, bicicletas el\u00e9ctricas, motocicletas y camiones, y sus ventas anuales alcanzan los 150 millones de d\u00f3lares. SEYOUN tire es uno de los 3 principales fabricantes de neum\u00e1ticos para motocicletas y scooters en China, y hemos invertido 3 mil millones de RMB en 2021 para lanzar la l\u00ednea de producci\u00f3n totalmente autom\u00e1tica para realizar la primera industria 4.0 real en China. SEYOUN Tire ha obtenido los certificados ISO9001, CCC, E-MARK, ECE, SNI y DOT. Con nuestra certificaci\u00f3n del sistema de gesti\u00f3n de calidad ISO9001 y la certificaci\u00f3n obligatoria de productos (certificaci\u00f3n 3C), hemos establecido un sistema y procesos integrales de gesti\u00f3n de calidad. <\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4292\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5de5\u5382\u8be6\u60c5\u56fe-300x266.jpg\" alt=\"\" width=\"539\" height=\"478\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5de5\u5382\u8be6\u60c5\u56fe-300x266.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5de5\u5382\u8be6\u60c5\u56fe-14x12.jpg 14w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5de5\u5382\u8be6\u60c5\u56fe-600x532.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5de5\u5382\u8be6\u60c5\u56fe.jpg 750w\" sizes=\"(max-width: 539px) 100vw, 539px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4287\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u8bc1\u4e66-300x28.jpg\" alt=\"\" width=\"536\" height=\"50\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u8bc1\u4e66-300x28.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u8bc1\u4e66-18x2.jpg 18w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u8bc1\u4e66-600x56.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u8bc1\u4e66.jpg 750w\" sizes=\"(max-width: 536px) 100vw, 536px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4286\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u6469\u6258\u8f66\u91c7\u75282_08-300x131.jpg\" alt=\"\" width=\"543\" height=\"237\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u6469\u6258\u8f66\u91c7\u75282_08-300x131.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u6469\u6258\u8f66\u91c7\u75282_08-18x8.jpg 18w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u6469\u6258\u8f66\u91c7\u75282_08-600x262.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u6469\u6258\u8f66\u91c7\u75282_08.jpg 750w\" sizes=\"(max-width: 543px) 100vw, 543px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4288\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5c55\u4f1a\u56fe-300x300.jpg\" alt=\"\" width=\"521\" height=\"521\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5c55\u4f1a\u56fe-300x300.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5c55\u4f1a\u56fe-1024x1024.jpg 1024w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5c55\u4f1a\u56fe-150x150.jpg 150w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5c55\u4f1a\u56fe-768x768.jpg 768w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5c55\u4f1a\u56fe-12x12.jpg 12w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5c55\u4f1a\u56fe-600x600.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5c55\u4f1a\u56fe-100x100.jpg 100w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u5c55\u4f1a\u56fe.jpg 1200w\" sizes=\"(max-width: 521px) 100vw, 521px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4283\" src=\"http:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u88c5\u7bb1\u53d1\u8d27\u56fe-300x236.jpg\" alt=\"\" width=\"501\" height=\"394\" srcset=\"https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u88c5\u7bb1\u53d1\u8d27\u56fe-300x236.jpg 300w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u88c5\u7bb1\u53d1\u8d27\u56fe-15x12.jpg 15w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u88c5\u7bb1\u53d1\u8d27\u56fe-600x473.jpg 600w, https:\/\/www.seyountyre.com\/wp-content\/uploads\/2025\/03\/\u88c5\u7bb1\u53d1\u8d27\u56fe.jpg 750w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>&nbsp; JiangsuSanyuan Tire Co., Ltd (SEYOUN Tire),founded in 2001,is privately technology manufacturers of tires and tubes for bicycles, electric bicycles, motorcycles and trucks. SEYOUN headquater, as its main manufacturing base,Suqian Factory, founded on 7 July, 2007,is conveniently located at Suyu economy development district in Suqian city, Jiangsu province. Covering an area of 648 acres, with [&hellip;]<\/p>\n","protected":false},"featured_media":4000,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[45],"product_tag":[],"class_list":{"0":"post-4003","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-bicycle-tire","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.seyountyre.com\/es\/wp-json\/wp\/v2\/product\/4003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.seyountyre.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.seyountyre.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.seyountyre.com\/es\/wp-json\/wp\/v2\/comments?post=4003"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.seyountyre.com\/es\/wp-json\/wp\/v2\/media\/4000"}],"wp:attachment":[{"href":"https:\/\/www.seyountyre.com\/es\/wp-json\/wp\/v2\/media?parent=4003"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.seyountyre.com\/es\/wp-json\/wp\/v2\/product_brand?post=4003"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.seyountyre.com\/es\/wp-json\/wp\/v2\/product_cat?post=4003"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.seyountyre.com\/es\/wp-json\/wp\/v2\/product_tag?post=4003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}